{"id":217,"date":"2023-12-13T15:26:57","date_gmt":"2023-12-13T15:26:57","guid":{"rendered":"https:\/\/raluxsolar.com\/2023\/?page_id=217"},"modified":"2024-08-01T17:04:14","modified_gmt":"2024-08-01T17:04:14","slug":"carports","status":"publish","type":"page","link":"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/carports\/","title":{"rendered":"Carports"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light editorskit-no-desktop\" style=\"min-height:503px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim has-background-gradient\" style=\"background:linear-gradient(80deg,rgb(255,255,255) 39%,rgba(255,255,255,0) 39%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1919\" class=\"wp-block-cover__image-background wp-image-726\" alt=\"\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-scaled.jpg\" style=\"object-position:47% 40%\" data-object-fit=\"cover\" data-object-position=\"47% 40%\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-scaled.jpg 2560w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-300x225.jpg 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-1024x767.jpg 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-768x576.jpg 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-1536x1151.jpg 1536w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-2048x1535.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:22.22%\">\n<div style=\"height:40px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-70 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-group is-layout-flex wp-container-core-group-is-layout-bbdd9cca wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group wp-container-content-9cfa9a5a is-vertical is-content-justification-left is-layout-flex wp-container-core-group-is-layout-084ae230 wp-block-group-is-layout-flex\">\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color wp-block-paragraph\" style=\"font-size:60px;font-style:normal;font-weight:700;letter-spacing:-2px;line-height:0.8;text-transform:uppercase\">sistemas<strong> <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color wp-block-paragraph\" style=\"font-size:62px;font-style:normal;font-weight:700;letter-spacing:-2px;line-height:0.8;text-transform:uppercase\"><strong>CARPORT<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"90\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones.png\" alt=\"\" class=\"wp-image-2308\" style=\"width:253px;height:auto\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones.png 400w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones-300x68.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:0px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-cf2db169\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/sistemas-de-montaje\/\">DESCARGAR CAT\u00c1LOGO \u2192<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:44.45%\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull editorskit-no-tablet editorskit-no-mobile\" style=\"min-height:503px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-90 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background:linear-gradient(80deg,rgb(255,255,255) 39%,rgba(255,255,255,0) 39%)\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1919\" class=\"wp-block-cover__image-background wp-image-726\" alt=\"\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-scaled.jpg\" style=\"object-position:47% 40%\" data-object-fit=\"cover\" data-object-position=\"47% 40%\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-scaled.jpg 2560w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-300x225.jpg 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-1024x767.jpg 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-768x576.jpg 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-1536x1151.jpg 1536w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2023\/12\/montaje-de-proyecto-ralux-2048x1535.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns alignfull are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:22.22%\">\n<div style=\"height:40px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flex wp-container-core-group-is-layout-bbdd9cca wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group wp-container-content-9cfa9a5a is-vertical is-content-justification-left is-layout-flex wp-container-core-group-is-layout-084ae230 wp-block-group-is-layout-flex\">\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color wp-block-paragraph\" style=\"font-size:60px;font-style:normal;font-weight:700;letter-spacing:-2px;line-height:0.8;text-transform:uppercase\">sistemas<strong> <\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color wp-block-paragraph\" style=\"font-size:62px;font-style:normal;font-weight:700;letter-spacing:-2px;line-height:0.8;text-transform:uppercase\"><strong>CARPORT<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"90\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones.png\" alt=\"\" class=\"wp-image-2308\" style=\"width:253px;height:auto\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones.png 400w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/certificaiones-300x68.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:0px;width:0px\" aria-hidden=\"true\" class=\"wp-block-spacer wp-container-content-cf2db169\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/sistemas-de-montaje\/\">DESCARGAR CAT\u00c1LOGO \u2192<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:44.45%\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light has-parallax\" style=\"min-height:450px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-80 has-background-dim\" style=\"background-color:#f2f2f2\"><\/span><div class=\"wp-block-cover__image-background wp-image-2088 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-ralux.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_left coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInLeft\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-9bbe122eb84faad3c2b1ff9ef95acab6\" style=\"font-style:normal;font-weight:700\">MILANO<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-milano-ralux-solar.png\" alt=\"\" class=\"wp-image-2592\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-milano-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-milano-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-milano-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar.png\" alt=\"\" class=\"wp-image-2392\" style=\"object-fit:cover\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar.png 1920w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-milano-ralux-solar-1536x864.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-b724b7f4db3f8d94556e1356638ab477 wp-block-paragraph\"><strong>El Carport Milano es una p\u00e9rgola que permite la instalaci\u00f3n de 3 m\u00f3dulos fotovoltaicos verticalmente. La estructura es totalmente de aluminio anodizado mientras que las bases son de acero galvanizado en caliente. Es posible espaciar las columnas hasta 5.50mt<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-milano\/\">EXPLORA \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_right coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInRight\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-46a75ed229127db40986b24fa78a3493\" style=\"font-style:normal;font-weight:700\">FIRENZE MONO \/ INVERTIDO<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png\" alt=\"\" class=\"wp-image-2596\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar-1024x576.png\" alt=\"\" class=\"wp-image-2395\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar-1536x864.png 1536w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-mono-e-inverso-ralux-solar.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-9194b394a05746d765316c3938862c90 wp-block-paragraph\"><strong>El Carport Firenze es un carport que permite la instalaci\u00f3n de 3-4-6-8 m\u00f3dulos fotovoltaicos vertical u horizontalmente. La estructura de la capota es de acero galvanizado en caliente, mientras que las correas y todos los accesorios son de aluminio anodizado. <\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-firenze\/\">FIRENZE MONO \u2192<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-firenze-invertido\/\">FIRENZE INVERTIDO \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull has-parallax\" style=\"min-height:140px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-neve-link-hover-color-background-color has-background-dim\"><\/span><div role=\"img\" class=\"wp-block-cover__image-background wp-image-2088 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-ralux.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-nv-site-bg-color has-text-color has-link-color has-large-font-size wp-elements-f80d5ec13b6ea8695bea89e580c643fc wp-block-paragraph\" style=\"font-style:normal;font-weight:400\"><strong>COTIZA TU PROYECTO CON NOSOTROS<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-primary\"><a class=\"wp-block-button__link wp-element-button\">CONTACTO<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light has-parallax\" style=\"min-height:450px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-80 has-background-dim\" style=\"background-color:#f2f2f2\"><\/span><div class=\"wp-block-cover__image-background wp-image-2088 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-ralux.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_left coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInLeft\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-70 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-bb9c2aa487da93a756d791f4f4a04a36\" style=\"font-style:normal;font-weight:700\">FIRENZE DUO<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png\" alt=\"\" class=\"wp-image-2596\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar.png\" alt=\"\" class=\"wp-image-2398\" style=\"object-fit:cover\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar.png 1920w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-duo-ralux-solar-1536x864.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-88f1ed0bb4603540aa740e07714ed5cf wp-block-paragraph\"><strong>El Carport Firenze es un carport que permite la instalaci\u00f3n de 3-4-6-8 m\u00f3dulos fotovoltaicos vertical u horizontalmente. La estructura de la capota es de acero galvanizado en caliente, mientras que las correas y todos los accesorios son de aluminio anodizado. Es posible espaciar las columnas hasta 5,70 metros y la altura de las mismas se puede cambiar a petici\u00f3n.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-firenze-duo\/\">EXPLORA \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_right coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInRight\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-800553a0243195efe891f23471c2ef3b\" style=\"font-style:normal;font-weight:700\">FIRENZE LONG \/ BIG WAVE<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png\" alt=\"\" class=\"wp-image-2596\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar-1024x576.png\" alt=\"\" class=\"wp-image-2401\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar-1536x864.png 1536w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-firenze-long-y-big-wave-ralux-solar.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-88f1ed0bb4603540aa740e07714ed5cf wp-block-paragraph\"><strong>El Carport Firenze es un carport que permite la instalaci\u00f3n de 3-4-6-8 m\u00f3dulos fotovoltaicos vertical u horizontalmente. La estructura de la capota es de acero galvanizado en caliente, mientras que las correas y todos los accesorios son de aluminio anodizado. Es posible espaciar las columnas hasta 5,70 metros y la altura de las mismas se puede cambiar a petici\u00f3n.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-firenze-long\/\">FIRENZE LONG \u2192<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/firenze-big-wave\/\">FIRENZE BIG WAVE \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light has-parallax\" style=\"min-height:450px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-80 has-background-dim\" style=\"background-color:#f2f2f2\"><\/span><div class=\"wp-block-cover__image-background wp-image-2088 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-ralux.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_left coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInLeft\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-feed13dba3dee26a31b8e75325724dd0\" style=\"font-style:normal;font-weight:700\">ROMA<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png\" alt=\"\" class=\"wp-image-2596\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar.png\" alt=\"\" class=\"wp-image-2404\" style=\"object-fit:cover\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar.png 1920w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-1-ralux-solar-1536x864.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-e8ad155fdbe5d64507783e64578fe20b wp-block-paragraph\"><strong>El Carport Roma es un carport que permite la instalaci\u00f3n de paneles en configuraci\u00f3n 3-4-5-6 vertical u horizontalmente. La estructura de la capota es de acero galvanizado en caliente, mientras que las correas y todos los accesorios son de aluminio anodizado. Es posible espaciar las columnas hasta 7,00 metros y la altura de las mismas se puede cambiar a petici\u00f3n del cliente.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-roma\/\">EXPLORA \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top button_slide slide_right coblocks-animate is-layout-flow wp-block-column-is-layout-flow\" data-coblocks-animation=\"slideInRight\">\n<div class=\"wp-block-cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-80 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-neve-link-color-color has-text-color has-link-color has-medium-font-size wp-elements-44dab5a980b1f9000684c875fcccc251 wp-block-paragraph\" style=\"font-style:normal;font-weight:400\">CARPORT<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-neve-text-color-color has-text-color has-link-color has-x-large-font-size wp-elements-eba42323263e8258cac81c78c4d6fb09\" style=\"font-style:normal;font-weight:700\">ROMA<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"200\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png\" alt=\"\" class=\"wp-image-2596\" style=\"width:auto;height:45px\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar.png 907w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-300x66.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/atributos-sistema-firenze-ralux-solar-768x169.png 768w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar-1024x576.png\" alt=\"\" class=\"wp-image-2407\" srcset=\"https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar-1024x576.png 1024w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar-300x169.png 300w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar-768x432.png 768w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar-1536x864.png 1536w, https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-roma-2-ralux-solar.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left has-neve-text-color-color has-text-color has-link-color wp-elements-b8e77e2136398dca7b2853df37d0f504 wp-block-paragraph\"><strong>Varias configuraciones est\u00e1n disponibles tanto en horizontal como vertical y es posible elegir el grado de galvanizaci\u00f3n dependiendo del sitio de instalaci\u00f3n.<br>Este modelo de estructura se puede adaptar para proyectos agro voltaicos.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-89b4c9e9 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-secondary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/carport-roma\/\">EXPLORA \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull has-parallax wp-duotone-rgb4448102-ffb23d-1\" style=\"margin-top:0;padding-top:4vw;padding-right:4vw;padding-bottom:4vw;padding-left:4vw;min-height:140px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-neve-link-color-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__image-background wp-image-2088 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/raluxsolar.com\/2023\/wp-content\/uploads\/2024\/02\/carport-ralux.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-nv-site-bg-color has-text-color wp-block-paragraph\" style=\"font-size:35px;font-style:normal;font-weight:700;letter-spacing:0px;line-height:0.9;text-transform:uppercase\">CUENTANOS TU NECESIDAD \u00a1TE ASESORAREMOS!<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-default\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/raluxsolar.com\/2023\/es\/contacto\/\">CONTACTO \u2192<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-color has-white-color has-black-background-color has-text-color has-background has-link-color wp-elements-2aab0bf934c260b5db498faf918a5a75 is-nowrap is-layout-flex wp-container-core-group-is-layout-8e373281 wp-block-group-is-layout-flex\" style=\"min-height:40vh;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40)\">\n<div class=\"wp-block-columns alignwide is-style-default is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"font-size:10px;text-transform:uppercase\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p class=\"has-text-align-left has-nv-site-bg-color has-text-color has-link-color wp-elements-6ffd74048beb448d86063673cbe1f58e wp-block-paragraph\" style=\"font-size:12px;font-style:normal;font-weight:700;text-transform:uppercase\">Productos<\/p>\n\n\n\n<div class=\"wp-block-group parjunto is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-4d06a5dfad3e2be733d217e15f7b7cc2 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/sistemas-aerodinamicos\/\" class=\"ek-link\">Sistemas aerodin\u00e1micos<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-3c8dd093e3eea20d10ea978e44882f2a wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/cubiertas-inclinadas\/\" class=\"ek-link\">Cubiertas inclinadas<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-b05ee7b9886f4d5dea3266a3d3b08788 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/sistemas-anclados\/\" class=\"ek-link\">Sistemas anclados<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-cdf44cefd46779d10c6164281c05af5f wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/parques-solares\/\" class=\"ek-link\">Parques solares<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-0258678a75370aecb02ff1a9a1234897 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/sistemas-de-montaje\/carports\/\" class=\"ek-link\">Carports<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p class=\"has-text-align-left has-nv-site-bg-color has-text-color has-link-color wp-elements-c965ae945ef6d232aa97fa57968a7b20 wp-block-paragraph\" style=\"font-size:12px;font-style:normal;font-weight:700;text-transform:uppercase\">empresa<\/p>\n\n\n\n<div class=\"wp-block-group parjunto is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-5660632952ac877eacb9eac382fb5b80 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/somos\/\" class=\"ek-link\">Nuestra historia<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-8a7849614aac1856e8583401b1b1e5ab wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/trabaja-con-nosotros\/\" class=\"ek-link\">Trabaja con Nosotros<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-e7dd973addba0a10b72bad87f7fe3d6f wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/catalogo2222\/\" class=\"ek-link\">Cat\u00e1logo<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-5d3c52cbf8f0564ee15ae650e8e16645 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/proyectos\/\" class=\"ek-link\">Proyectos<\/a><\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-2157e3998045826a0d7e3bee8ee48732 wp-block-paragraph\"><a href=\"https:\/\/raluxsolar.com\/2023\/es\/blog\/\" class=\"ek-link\">Blog<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p class=\"has-text-align-left has-nv-site-bg-color has-text-color has-link-color wp-elements-3b69911517521ed73d763fe46e8424a5 wp-block-paragraph\" style=\"font-size:12px;font-style:normal;font-weight:700;text-transform:uppercase\">ingenieria<\/p>\n\n\n\n<div class=\"wp-block-group parjunto is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-54dbcfb2fccd8f74db0a2f053ad75fd5 wp-block-paragraph\">Fichas t\u00e9cnicas<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-41df090451dd58bc483af990a190ac34 wp-block-paragraph\">Manuales de instalaci\u00f3n<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-d3c11d3cf97bb4b4fbebe1d0926f4dcf wp-block-paragraph\">Fichas de producto<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<p class=\"has-text-align-left has-nv-site-bg-color has-text-color has-link-color wp-elements-e06293fb86509746b67c95365e193d0b wp-block-paragraph\" style=\"font-size:12px;font-style:normal;font-weight:700;text-transform:uppercase\">contactos<\/p>\n\n\n\n<div class=\"wp-block-group parjunto is-vertical is-layout-flex wp-container-core-group-is-layout-dc24fb03 wp-block-group-is-layout-flex\" style=\"padding-top:0;padding-bottom:0\">\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-b90e675674e03f24b588a6eaf1c2798d wp-block-paragraph\">Italia<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-5b5ac2864268efb9445357d9ab7abd47 wp-block-paragraph\">Colombia<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-bc28ece82d35e493b7f6fa01a7020fa0 wp-block-paragraph\">M\u00e9xico<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-2509e8ba81483e2be7233d1f1627ffcc wp-block-paragraph\">Europa<\/p>\n\n\n\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-dee635cb5799f991cdb6f968e2948b7f wp-block-paragraph\">LATAM<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:17%\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"has-nv-site-bg-color has-text-color has-link-color wp-elements-463efb6bb09e46dee98b30517606d024 wp-block-paragraph\">Siguenos<\/p>\n\n\n\n<ul class=\"wp-block-social-links has-icon-color has-icon-background-color is-style-default is-nowrap is-layout-flex wp-container-core-social-links-is-layout-8f761849 wp-block-social-links-is-layout-flex\"><li style=\"color:var(--nv-site-bg);background-color:var(--nv-dark-bg)\" class=\"wp-social-link wp-social-link-linkedin has-nv-site-bg-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.linkedin.com\/company\/ralux\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li>\n\n<li style=\"color:var(--nv-site-bg);background-color:var(--nv-dark-bg)\" class=\"wp-social-link wp-social-link-instagram has-nv-site-bg-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/raluxsolar\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n\n\n<li style=\"color:var(--nv-site-bg);background-color:var(--nv-dark-bg)\" class=\"wp-social-link wp-social-link-facebook has-nv-site-bg-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/raluxsolar\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li style=\"color:var(--nv-site-bg);background-color:var(--nv-dark-bg)\" class=\"wp-social-link wp-social-link-youtube has-nv-site-bg-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/channel\/UCEA0RXc93mp2SmUCdYzfWPQ\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M21.8,8.001c0,0-0.195-1.378-0.795-1.985c-0.76-0.797-1.613-0.801-2.004-0.847c-2.799-0.202-6.997-0.202-6.997-0.202 h-0.009c0,0-4.198,0-6.997,0.202C4.608,5.216,3.756,5.22,2.995,6.016C2.395,6.623,2.2,8.001,2.2,8.001S2,9.62,2,11.238v1.517 c0,1.618,0.2,3.237,0.2,3.237s0.195,1.378,0.795,1.985c0.761,0.797,1.76,0.771,2.205,0.855c1.6,0.153,6.8,0.201,6.8,0.201 s4.203-0.006,7.001-0.209c0.391-0.047,1.243-0.051,2.004-0.847c0.6-0.607,0.795-1.985,0.795-1.985s0.2-1.618,0.2-3.237v-1.517 C22,9.62,21.8,8.001,21.8,8.001z M9.935,14.594l-0.001-5.62l5.404,2.82L9.935,14.594z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">YouTube<\/span><\/a><\/li><\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2215,"parent":406,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"on","neve_meta_reading_time":"","footnotes":""},"class_list":["post-217","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/pages\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/comments?post=217"}],"version-history":[{"count":45,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/pages\/217\/revisions"}],"predecessor-version":[{"id":5980,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/pages\/217\/revisions\/5980"}],"up":[{"embeddable":true,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/pages\/406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/media\/2215"}],"wp:attachment":[{"href":"https:\/\/raluxsolar.com\/2023\/es\/wp-json\/wp\/v2\/media?parent=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}